{"id":3082,"date":"2021-11-06T14:13:10","date_gmt":"2021-11-06T14:13:10","guid":{"rendered":"https:\/\/faza.eu\/faza-design\/faza-design-blanco\/"},"modified":"2021-11-06T14:13:10","modified_gmt":"2021-11-06T14:13:10","slug":"faza-design-blanco","status":"publish","type":"page","link":"https:\/\/faza.eu\/es\/fachada\/faza-design\/faza-design-blanco\/","title":{"rendered":"faza design blanco"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":2881,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-3082","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>faza design blanco - Faza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/faza.eu\/es\/fachada\/faza-design\/faza-design-blanco\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"faza design blanco - Faza\" \/>\n<meta property=\"og:url\" content=\"https:\/\/faza.eu\/es\/fachada\/faza-design\/faza-design-blanco\/\" \/>\n<meta property=\"og:site_name\" content=\"Faza\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/faza.eu\/es\/fachada\/faza-design\/faza-design-blanco\/\",\"url\":\"https:\/\/faza.eu\/es\/fachada\/faza-design\/faza-design-blanco\/\",\"name\":\"faza design blanco - Faza\",\"isPartOf\":{\"@id\":\"https:\/\/faza.eu\/es\/#website\"},\"datePublished\":\"2021-11-06T14:13:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/faza.eu\/es\/fachada\/faza-design\/faza-design-blanco\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/faza.eu\/es\/fachada\/faza-design\/faza-design-blanco\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/faza.eu\/es\/fachada\/faza-design\/faza-design-blanco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/faza.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"fachada\",\"item\":\"https:\/\/faza.eu\/es\/fachada\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"faza design\",\"item\":\"https:\/\/faza.eu\/es\/fachada\/faza-design\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"faza design blanco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/faza.eu\/es\/#website\",\"url\":\"https:\/\/faza.eu\/es\/\",\"name\":\"Faza\",\"description\":\"Bardages Faza | Le bardage vraiment sans obstacle\",\"publisher\":{\"@id\":\"https:\/\/faza.eu\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/faza.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/faza.eu\/es\/#organization\",\"name\":\"faza\",\"url\":\"https:\/\/faza.eu\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/faza.eu\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/faza.eu\/wp-content\/uploads\/2021\/04\/Faza-logo-gekleurd_Tekengebied-1.png\",\"contentUrl\":\"https:\/\/faza.eu\/wp-content\/uploads\/2021\/04\/Faza-logo-gekleurd_Tekengebied-1.png\",\"width\":280,\"height\":110,\"caption\":\"faza\"},\"image\":{\"@id\":\"https:\/\/faza.eu\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"faza design blanco - Faza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/faza.eu\/es\/fachada\/faza-design\/faza-design-blanco\/","og_locale":"es_ES","og_type":"article","og_title":"faza design blanco - Faza","og_url":"https:\/\/faza.eu\/es\/fachada\/faza-design\/faza-design-blanco\/","og_site_name":"Faza","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/faza.eu\/es\/fachada\/faza-design\/faza-design-blanco\/","url":"https:\/\/faza.eu\/es\/fachada\/faza-design\/faza-design-blanco\/","name":"faza design blanco - Faza","isPartOf":{"@id":"https:\/\/faza.eu\/es\/#website"},"datePublished":"2021-11-06T14:13:10+00:00","breadcrumb":{"@id":"https:\/\/faza.eu\/es\/fachada\/faza-design\/faza-design-blanco\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/faza.eu\/es\/fachada\/faza-design\/faza-design-blanco\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/faza.eu\/es\/fachada\/faza-design\/faza-design-blanco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/faza.eu\/es\/"},{"@type":"ListItem","position":2,"name":"fachada","item":"https:\/\/faza.eu\/es\/fachada\/"},{"@type":"ListItem","position":3,"name":"faza design","item":"https:\/\/faza.eu\/es\/fachada\/faza-design\/"},{"@type":"ListItem","position":4,"name":"faza design blanco"}]},{"@type":"WebSite","@id":"https:\/\/faza.eu\/es\/#website","url":"https:\/\/faza.eu\/es\/","name":"Faza","description":"Bardages Faza | Le bardage vraiment sans obstacle","publisher":{"@id":"https:\/\/faza.eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/faza.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/faza.eu\/es\/#organization","name":"faza","url":"https:\/\/faza.eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/faza.eu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/faza.eu\/wp-content\/uploads\/2021\/04\/Faza-logo-gekleurd_Tekengebied-1.png","contentUrl":"https:\/\/faza.eu\/wp-content\/uploads\/2021\/04\/Faza-logo-gekleurd_Tekengebied-1.png","width":280,"height":110,"caption":"faza"},"image":{"@id":"https:\/\/faza.eu\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/faza.eu\/es\/wp-json\/wp\/v2\/pages\/3082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/faza.eu\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/faza.eu\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/faza.eu\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/faza.eu\/es\/wp-json\/wp\/v2\/comments?post=3082"}],"version-history":[{"count":0,"href":"https:\/\/faza.eu\/es\/wp-json\/wp\/v2\/pages\/3082\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/faza.eu\/es\/wp-json\/wp\/v2\/pages\/2881"}],"wp:attachment":[{"href":"https:\/\/faza.eu\/es\/wp-json\/wp\/v2\/media?parent=3082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}